{"id":81120,"date":"2025-11-13T18:31:10","date_gmt":"2025-11-13T17:31:10","guid":{"rendered":"https:\/\/cncfilters.com\/?post_type=product&#038;p=81120"},"modified":"2026-02-28T18:09:02","modified_gmt":"2026-02-28T17:09:02","slug":"grove-gmk-4075-filter-99077npp","status":"publish","type":"product","link":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/","title":{"rendered":"GROVE GMK 4075 filter 99077NPP"},"content":{"rendered":"<p>We only deliver for free of charge within the European Union<br \/>\nIf you are a\u00a0 non-EU customer then all duty requirements are on your side.<\/p>\n<p>\u201cAll online filter supply offered parts are equivalent products to or interchangeable with original manufacturer parts, the original part names are used for cross reference only\u201d<\/p>\n<p>**Image may vary**<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GROVE GMK 4075 filter 99077NPP<\/p>\n<p>The best quality equivalent cartridge filter<\/p>\n<p><strong style=\"font-style: inherit;\">Dimensions &amp; details:<\/strong><\/p>\n<blockquote><p>Brand: Cronne Industry<br \/>\nD1: 129.000<br \/>\nD2: 69.000<br \/>\nD3: 69.000<br \/>\nH1: 400.000<br \/>\nFiltration accuracy (\u00b5):5 mic<\/p><\/blockquote>\n<p style=\"font-style: inherit; font-weight: inherit;\"><strong style=\"font-style: inherit;\"><em>Quantity: 3 pcs <strong>(1set)<\/strong><\/em><\/strong><\/p>\n<blockquote>\n<p style=\"font-style: inherit; font-weight: inherit;\"><em>Made in EU<\/em><\/p>\n<\/blockquote>\n<p><strong>Availability means how many sets we have in stock<\/strong><\/p>\n","protected":false},"featured_media":81122,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[61],"product_cat":[40],"product_tag":[111],"class_list":{"0":"post-81120","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-cronne-industry","7":"product_cat-cartridge-filter","8":"product_tag-grove-gmk-4075-filter","9":"desktop-align-center","10":"tablet-align-left","11":"mobile-align-left","13":"first","14":"outofstock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GROVE GMK 4075 filter 99077NPP - cncfilters.com<\/title>\n<meta name=\"description\" content=\"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions &amp; details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GROVE GMK 4075 filter 99077NPP - cncfilters.com\" \/>\n<meta property=\"og:description\" content=\"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions &amp; details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/\" \/>\n<meta property=\"og:site_name\" content=\"cncfilters.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-28T17:09:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cncfilters.com\/wp-content\/uploads\/2025\/11\/GROVE-GMK-4075-cartridge-filter-99077NPP-683x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/\",\"url\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/\",\"name\":\"GROVE GMK 4075 filter 99077NPP - cncfilters.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cncfilters.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GROVE-GMK-4075-cartridge-filter-99077NPP.png\",\"datePublished\":\"2025-11-13T17:31:10+00:00\",\"dateModified\":\"2026-02-28T17:09:02+00:00\",\"description\":\"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions & details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cncfilters.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GROVE-GMK-4075-cartridge-filter-99077NPP.png\",\"contentUrl\":\"https:\\\/\\\/cncfilters.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/GROVE-GMK-4075-cartridge-filter-99077NPP.png\",\"width\":1024,\"height\":1536,\"caption\":\"GROVE GMK 4075 filter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/product\\\/grove-gmk-4075-filter-99077npp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/cncfilters.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/cncfilters.com\\\/index.php\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GROVE GMK 4075 filter 99077NPP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#website\",\"url\":\"https:\\\/\\\/cncfilters.com\\\/\",\"name\":\"cncfilters.com\",\"description\":\"cncfilters.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cncfilters.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#organization\",\"name\":\"Hydrotrade Poland\",\"alternateName\":\"cncfilters.com\",\"url\":\"https:\\\/\\\/cncfilters.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cncfilters.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cncfilters.logo-nowe.jpg\",\"contentUrl\":\"https:\\\/\\\/cncfilters.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cncfilters.logo-nowe.jpg\",\"width\":1236,\"height\":499,\"caption\":\"Hydrotrade Poland\"},\"image\":{\"@id\":\"https:\\\/\\\/cncfilters.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GROVE GMK 4075 filter 99077NPP - cncfilters.com","description":"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions & details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/","og_locale":"en_US","og_type":"article","og_title":"GROVE GMK 4075 filter 99077NPP - cncfilters.com","og_description":"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions & details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000","og_url":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/","og_site_name":"cncfilters.com","article_modified_time":"2026-02-28T17:09:02+00:00","og_image":[{"width":683,"height":1024,"url":"https:\/\/cncfilters.com\/wp-content\/uploads\/2025\/11\/GROVE-GMK-4075-cartridge-filter-99077NPP-683x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/","url":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/","name":"GROVE GMK 4075 filter 99077NPP - cncfilters.com","isPartOf":{"@id":"https:\/\/cncfilters.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/#primaryimage"},"image":{"@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/#primaryimage"},"thumbnailUrl":"https:\/\/cncfilters.com\/wp-content\/uploads\/2025\/11\/GROVE-GMK-4075-cartridge-filter-99077NPP.png","datePublished":"2025-11-13T17:31:10+00:00","dateModified":"2026-02-28T17:09:02+00:00","description":"GROVE GMK 4075 cartridge filter 99077NPP, The best quality equivalent cartridge filterDimensions & details:D1: 129.000D2: 69.000D3: 69.000H1: 400.000","breadcrumb":{"@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/#primaryimage","url":"https:\/\/cncfilters.com\/wp-content\/uploads\/2025\/11\/GROVE-GMK-4075-cartridge-filter-99077NPP.png","contentUrl":"https:\/\/cncfilters.com\/wp-content\/uploads\/2025\/11\/GROVE-GMK-4075-cartridge-filter-99077NPP.png","width":1024,"height":1536,"caption":"GROVE GMK 4075 filter"},{"@type":"BreadcrumbList","@id":"https:\/\/cncfilters.com\/index.php\/product\/grove-gmk-4075-filter-99077npp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/cncfilters.com\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/cncfilters.com\/index.php\/store\/"},{"@type":"ListItem","position":3,"name":"GROVE GMK 4075 filter 99077NPP"}]},{"@type":"WebSite","@id":"https:\/\/cncfilters.com\/#website","url":"https:\/\/cncfilters.com\/","name":"cncfilters.com","description":"cncfilters.com","publisher":{"@id":"https:\/\/cncfilters.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cncfilters.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cncfilters.com\/#organization","name":"Hydrotrade Poland","alternateName":"cncfilters.com","url":"https:\/\/cncfilters.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cncfilters.com\/#\/schema\/logo\/image\/","url":"https:\/\/cncfilters.com\/wp-content\/uploads\/2026\/03\/cncfilters.logo-nowe.jpg","contentUrl":"https:\/\/cncfilters.com\/wp-content\/uploads\/2026\/03\/cncfilters.logo-nowe.jpg","width":1236,"height":499,"caption":"Hydrotrade Poland"},"image":{"@id":"https:\/\/cncfilters.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product\/81120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/comments?post=81120"}],"version-history":[{"count":6,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product\/81120\/revisions"}],"predecessor-version":[{"id":81731,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product\/81120\/revisions\/81731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/media\/81122"}],"wp:attachment":[{"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/media?parent=81120"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=81120"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=81120"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cncfilters.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=81120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}